{"id":277,"count":7,"description":"Dietro ogni percorso psicologico ci sono scelte, valori e responsabilit\u00e0. In questa sezione le psicologhe e gli psicologi di Tice condividono riflessioni sulla professione, sull'etica, sulla sicurezza e sui principi che orientano il lavoro clinico, per rendere pi\u00f9 trasparente e comprensibile ci\u00f2 che accade dentro e intorno alla cura.\r\n","link":"https:\/\/centrotice.it\/en\/categoria\/valori-pratica-psicologica\/","name":"Valori e pratica psicologica","slug":"valori-pratica-psicologica","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/centrotice.it\/en\/wp-json\/wp\/v2\/categories\/277"}],"collection":[{"href":"https:\/\/centrotice.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/centrotice.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/centrotice.it\/en\/wp-json\/wp\/v2\/posts?categories=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}